{"id":4623,"date":"2021-07-20T10:40:31","date_gmt":"2021-07-20T08:40:31","guid":{"rendered":"https:\/\/sockenseite.de\/wordpress\/2021\/07\/20\/piraten-zu-den-folgen-der-flutkatastrophe-politisch-verantwortliche-benennen\/"},"modified":"2022-04-01T12:00:59","modified_gmt":"2022-04-01T10:00:59","slug":"piraten-zu-den-folgen-der-flutkatastrophe-politisch-verantwortliche-benennen","status":"publish","type":"post","link":"https:\/\/sockenseite.de\/wordpress\/2021\/07\/20\/piraten-zu-den-folgen-der-flutkatastrophe-politisch-verantwortliche-benennen\/","title":{"rendered":"PIRATEN zu den Folgen der Flutkatastrophe: Politisch Verantwortliche benennen"},"content":{"rendered":"<p><strong><em>+++ Trotz rechtzeitiger Warnungen keine erkennbaren Schritte seitens der Landesregierung +++ Tote und Schwerverletzte h\u00e4tten vermieden werden k\u00f6nnen +++ Ministerpr\u00e4sident <a href=\"https:\/\/piratenpartei-leverkusen.de\/tag\/armin-laschet\/\">Armin Laschet<\/a> und Innenminister <a href=\"https:\/\/piratenpartei-leverkusen.de\/tag\/herbert-reul\/\">Herbert Reul<\/a> verantwortlich f\u00fcr die verheerenden Folgen der Flutkatastrophe +++ <\/em><\/strong><\/p>\n<p>Bereits am Sonntag, den 10. Juli, lag nach Recherchen des Redaktionsnetzwerk Deutschland (RND) <a href=\"https:\/\/www.rnd.de\/politik\/hochwasser-warnsystem-efas-warum-wurde-trotz-unwetter-warnung-nicht-evakuiert-fuer-hannah-cloke-ZDXP6DO5WVHWLIMYTAAYQEHWAM.html\">die erste Hochwasserwarnung der Stufe \u201eExtrem\u201c des European Flood Awareness System (EFAS)<\/a> vor. Auch das NRW-Innenministerium war schon Montag Vormittag alarmiert.<br \/>Am Mittwoch gab das <a href=\"https:\/\/www.efas.eu\/de\">EFAS<\/a> mit 90% \u00dcbereinstimmung die tats\u00e4chlich ab dem 14. Juli von \u00dcberflutungen betroffenen Kreise und St\u00e4dte an. Dass dort keine Evakuierung stattfand und die Einsatzkr\u00e4fte den Ereignissen nachlaufen mussten, bezeichnet Hannah Cloke, Professorin f\u00fcr Hydrologie an der britischen Universit\u00e4t Reading und eine der Entwicklerinnen des Europ\u00e4ischen Hochwasser-Warnsystems, als <a href=\"https:\/\/m.tagesspiegel.de\/politik\/monumentales-systemversagen-deutschland-war-praezise-gewarnt-die-menschen-aber-nicht\/27433034.html\">\u201emonumentales Systemversagen\u201c<\/a>.<\/p>\n<p><strong><a href=\"https:\/\/piratenpartei-leverkusen.de\/tag\/oliver-ding\/\">Oliver Ding<\/a>, B\u00fcropirat aus dem ebenfalls von verheerenden \u00dcberflutungen mit existenzbedrohenden Sch\u00e4den betroffenen Leverkusen, erl\u00e4utert:<\/strong><\/p>\n<blockquote class=\"wp-block-quote\">\n<p>\u201ePr\u00e4vention ist die wichtigste Aufgabe im <a href=\"https:\/\/piratenpartei-leverkusen.de\/tag\/katastrophenschutz\/\">Katastrophenschutz<\/a>. Die Beh\u00f6rden waren offenbar weit im Vorfeld informiert und haben dennoch nicht gehandelt. Die Bev\u00f6lkerung wurde <a href=\"https:\/\/www.piratenpartei-nrw.de\/2021\/07\/19\/starkregen-und-flutkatastrophe-nrw-war-nicht-gut-vorbereitet\/\">nicht ausreichend gewarnt<\/a>. Die Kommunen wurden allein gelassen. Die Einsatzkr\u00e4fte konnten sich nicht koordiniert vorbereiten und mussten auf die schon im Gang befindliche Katastrophe reagieren. Das hat Menschenleben gekostet.<\/p>\n<p>Wie es anders gehen kann und muss, zeigt das <a href=\"https:\/\/n-tv.de\/panorama\/Niederlande-trotzen-dem-Hochwasser-article22688563.html\">Beispiel der Niederlande<\/a>: Dort wurde auf die Warnungen reagiert, und es konnten Vorbereitungen getroffen werden. So sind neben den materiellen Sch\u00e4den keine Menschenleben oder auch nur Verletzte zu beklagen.\u201c<\/p>\n<\/blockquote>\n<p>Noch am Freitag, den 16. Juli <a href=\"https:\/\/www.ksta.de\/politik\/-nicht-erforderlich--kritik-an-landesregierung---warum-gibt-es-keinen-krisenstab--38912630?cb=1626699813690\">hielt man im Innenministerium einen Krisenstab unter F\u00fchrung der Landesregierung f\u00fcr unn\u00f6tig<\/a>. Da waren bereits weite Gebiete des Landes \u00fcberschwemmt und viele Menschen gestorben.<\/p>\n<blockquote class=\"wp-block-quote\">\n<p>\u201eDurch die Unt\u00e4tigkeit der Landesregierung wurde den Einsatzkr\u00e4ften wertvolle Vorbereitungszeit vorenthalten, um Personaleinsatz, Kommunikationswege und Infrastrukturen zu planen und zu verteilen und die besonders gef\u00e4hrdeten Orte zu evakuieren. Ein Innenminister, der entgegen der Faktenlage nachdr\u00fccklich von einer <a href=\"https:\/\/twitter.com\/WDRaktuell\/status\/1417121996052307971\">nicht vorhersehbaren Katastrophe<\/a> spricht, sollte sofort zur\u00fccktreten.<br \/>Wir fordern au\u00dferdem einen <a href=\"https:\/\/piratenpartei-leverkusen.de\/tag\/untersuchungsausschuss\/\">parlamentarischen Untersuchungsausschuss<\/a>, um die Verantwortlichen f\u00fcr das ersch\u00fctternde Organisationsversagen benennen zu k\u00f6nnen. Aus unserer Sicht hat die zur Schau gestellte Skepsis des Ministerpr\u00e4sidenten gegen\u00fcber Warnungen der Wissenschaft hier \u2013 wie schon in der <a href=\"https:\/\/piratenpartei-leverkusen.de\/tag\/coronavirus\/\">Corona-Pandemie<\/a> \u2013 erneut Menschenleben gefordert. Als Kanzler w\u00e4re er untragbar,\u201c<\/p>\n<\/blockquote>\n<p><strong>kommentiert <a href=\"https:\/\/piratenpartei-leverkusen.de\/tag\/helder-aguiar\/\">H\u00e9lder Aguiar<\/a>, politischer Gesch\u00e4ftsf\u00fchrer der Piratenpartei NRW.<\/strong><\/p>\n<p>Der Beitrag <a rel=\"nofollow\" href=\"https:\/\/piratenpartei-leverkusen.de\/2021\/07\/piraten-zu-den-folgen-der-flutkatastrophe-politisch-verantwortliche-benennen\/\">PIRATEN zu den Folgen der Flutkatastrophe: Politisch Verantwortliche benennen<\/a> erschien zuerst auf <a rel=\"nofollow\" href=\"https:\/\/piratenpartei-leverkusen.de\/\">Piratenpartei Leverkusen<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>+++ Trotz rechtzeitiger Warnungen keine erkennbaren Schritte seitens der Landesregierung +++ Tote und Schwerverletzte h\u00e4tten vermieden werden k\u00f6nnen +++ Ministerpr\u00e4sident Armin Laschet und&hellip;<\/p>\n","protected":false},"author":2,"featured_media":4624,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bluesky_dont_syndicate":"","_bluesky_syndication_accounts":"","_bluesky_syndication_text":"","footnotes":""},"categories":[683,22],"tags":[720,681,679,680,294],"class_list":["post-4623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-piraten","category-politik-und-gesellschaft","tag-helder-aguiar","tag-hochwasser","tag-katastrophenschutz","tag-klimakrise","tag-piraten"],"_links":{"self":[{"href":"https:\/\/sockenseite.de\/wordpress\/wp-json\/wp\/v2\/posts\/4623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sockenseite.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sockenseite.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sockenseite.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sockenseite.de\/wordpress\/wp-json\/wp\/v2\/comments?post=4623"}],"version-history":[{"count":0,"href":"https:\/\/sockenseite.de\/wordpress\/wp-json\/wp\/v2\/posts\/4623\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sockenseite.de\/wordpress\/wp-json\/wp\/v2\/media\/4624"}],"wp:attachment":[{"href":"https:\/\/sockenseite.de\/wordpress\/wp-json\/wp\/v2\/media?parent=4623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sockenseite.de\/wordpress\/wp-json\/wp\/v2\/categories?post=4623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sockenseite.de\/wordpress\/wp-json\/wp\/v2\/tags?post=4623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}} 